{"id":29255,"date":"2025-05-08T10:49:56","date_gmt":"2025-05-08T14:49:56","guid":{"rendered":"https:\/\/levasseur.org\/?p=29255"},"modified":"2025-05-08T10:49:56","modified_gmt":"2025-05-08T14:49:56","slug":"nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens","status":"publish","type":"post","link":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/","title":{"rendered":"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens"},"content":{"rendered":"<p><a href=\"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-29256 alignleft\" src=\"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-200x100.jpg 200w, https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg 300w, https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-400x200.jpg 400w, https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x.jpg 588w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Source : Journal de Qu\u00e9bec &#8211; Vincent Desbiens<br \/>\nMercredi, 7 mai 2025 14:33<\/p>\n<p>\u00ab\u00a0&#8230;Un seul nom devrait \u00eatre envisag\u00e9 pour nommer le nouveau complexe hospitalier du CHU de Qu\u00e9bec-Universit\u00e9 Laval, \u00e0 l\u2019issue du processus de consultation populaire, selon des historiens: celui d\u2019Irma LeVasseur.\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>suite : <a href=\"https:\/\/www.journaldequebec.com\/2025\/05\/07\/nom-recherche-pour-le-nouveau-complexe-hospitalier-du-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\">https:\/\/www.journaldequebec.com\/2025\/05\/07\/nom-recherche-pour-le-nouveau-complexe-hospitalier-du-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens<\/a><\/p>\n<p>&nbsp;<\/p>\n<p class=\"titre-principale\">\n","protected":false},"excerpt":{"rendered":"<p>Source : Journal de Qu\u00e9bec &#8211; Vincent Desbiens Mercredi, 7  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29255","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens - Familles Levasseur et Carmel<\/title>\n<meta name=\"description\" content=\"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens - Familles Levasseur et Carmel\" \/>\n<meta property=\"og:description\" content=\"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/\" \/>\n<meta property=\"og:site_name\" content=\"Familles Levasseur et Carmel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/associationlevasseur\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-08T14:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Levasseur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean-Pierre Levasseur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/\"},\"author\":{\"name\":\"Jean-Pierre Levasseur\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/person\\\/08aca2b2e8f0aaeb4fd1ba151d381668\"},\"headline\":\"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens\",\"datePublished\":\"2025-05-08T14:49:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/\"},\"wordCount\":62,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NCH_Irma@2x-300x150.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/\",\"url\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/\",\"name\":\"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens - Familles Levasseur et Carmel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NCH_Irma@2x-300x150.jpg\",\"datePublished\":\"2025-05-08T14:49:56+00:00\",\"description\":\"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NCH_Irma@2x-300x150.jpg\",\"contentUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NCH_Irma@2x-300x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/\",\"name\":\"Familles Levasseur & Carmel\",\"description\":\"Du mieux que je puis\",\"publisher\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#organization\",\"name\":\"Association des Levasseur d'Am\u00e9rique\",\"url\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/blason_nouv.gif\",\"contentUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/blason_nouv.gif\",\"width\":500,\"height\":487,\"caption\":\"Association des Levasseur d'Am\u00e9rique\"},\"image\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/associationlevasseur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/person\\\/08aca2b2e8f0aaeb4fd1ba151d381668\",\"name\":\"Jean-Pierre Levasseur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g\",\"caption\":\"Jean-Pierre Levasseur\"},\"description\":\"B\u00e9n\u00e9vole pour l'Association des Levasseur d'Am\u00e9rique depuis 1995.\",\"url\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens - Familles Levasseur et Carmel","description":"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/","og_locale":"fr_FR","og_type":"article","og_title":"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens - Familles Levasseur et Carmel","og_description":"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.","og_url":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/","og_site_name":"Familles Levasseur et Carmel","article_publisher":"https:\/\/www.facebook.com\/associationlevasseur","article_published_time":"2025-05-08T14:49:56+00:00","og_image":[{"url":"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg","type":"","width":"","height":""}],"author":"Jean-Pierre Levasseur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean-Pierre Levasseur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#article","isPartOf":{"@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/"},"author":{"name":"Jean-Pierre Levasseur","@id":"https:\/\/levasseur.org\/fr\/#\/schema\/person\/08aca2b2e8f0aaeb4fd1ba151d381668"},"headline":"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens","datePublished":"2025-05-08T14:49:56+00:00","mainEntityOfPage":{"@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/"},"wordCount":62,"commentCount":0,"publisher":{"@id":"https:\/\/levasseur.org\/fr\/#organization"},"image":{"@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#primaryimage"},"thumbnailUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/","url":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/","name":"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens - Familles Levasseur et Carmel","isPartOf":{"@id":"https:\/\/levasseur.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#primaryimage"},"image":{"@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#primaryimage"},"thumbnailUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg","datePublished":"2025-05-08T14:49:56+00:00","description":"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.","breadcrumb":{"@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#primaryimage","url":"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg","contentUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2025\/05\/NCH_Irma@2x-300x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/levasseur.org\/fr\/nch-chu-de-quebec-irma-levasseur-fait-consensus-chez-les-historiens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/levasseur.org\/fr\/"},{"@type":"ListItem","position":2,"name":"NCH -CHU de Qu\u00e9bec : Irma LeVasseur fait consensus chez les historiens"}]},{"@type":"WebSite","@id":"https:\/\/levasseur.org\/fr\/#website","url":"https:\/\/levasseur.org\/fr\/","name":"Familles Levasseur & Carmel","description":"Du mieux que je puis","publisher":{"@id":"https:\/\/levasseur.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/levasseur.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/levasseur.org\/fr\/#organization","name":"Association des Levasseur d'Am\u00e9rique","url":"https:\/\/levasseur.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/levasseur.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/04\/blason_nouv.gif","contentUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/04\/blason_nouv.gif","width":500,"height":487,"caption":"Association des Levasseur d'Am\u00e9rique"},"image":{"@id":"https:\/\/levasseur.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/associationlevasseur"]},{"@type":"Person","@id":"https:\/\/levasseur.org\/fr\/#\/schema\/person\/08aca2b2e8f0aaeb4fd1ba151d381668","name":"Jean-Pierre Levasseur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g","caption":"Jean-Pierre Levasseur"},"description":"B\u00e9n\u00e9vole pour l'Association des Levasseur d'Am\u00e9rique depuis 1995.","url":"https:\/\/levasseur.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/posts\/29255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/comments?post=29255"}],"version-history":[{"count":0,"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/posts\/29255\/revisions"}],"wp:attachment":[{"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/media?parent=29255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/categories?post=29255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/levasseur.org\/fr\/wp-json\/wp\/v2\/tags?post=29255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}