{"id":14495,"date":"2019-09-15T05:50:48","date_gmt":"2019-09-15T09:50:48","guid":{"rendered":"https:\/\/levasseur.org\/?p=14495"},"modified":"2019-09-20T14:43:17","modified_gmt":"2019-09-20T18:43:17","slug":"the-2019-rally-a-complete-success","status":"publish","type":"post","link":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/","title":{"rendered":"The 2019 gathering, a great success"},"content":{"rendered":"<p><a href=\"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg\"><img decoding=\"async\" class=\"lazyload wp-image-14504 alignleft\" src=\"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg\" data-orig-src=\"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg\" alt=\"\" width=\"195\" height=\"146\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27195%27%20height%3D%27146%27%20viewBox%3D%270%200%20195%20146%27%3E%3Crect%20width%3D%27195%27%20height%3D%27146%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1-200x150.jpg 200w, https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1-300x225.jpg 300w, https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1-400x300.jpg 400w, https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1-600x450.jpg 600w, https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg 640w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 195px) 100vw, 195px\" \/><\/a>More than 50 people gathered in Qu\u00e9bec City on September 14, 2019 to attend the Levasseur gathering. Photos and a summary of this gathering will soon be available on the Levasseur.org website. Thank you for participating.<\/p>\n<p><a href=\"https:\/\/levasseur.org\/doc\/reunions\/quebec_2019\/presentation\/ALA_Presentation_PDF.pdf\">https:\/\/levasseur.org\/doc\/reunions\/quebec_2019\/presentation\/ALA_Presentation_PDF.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>More than 50 people gathered in Qu\u00e9bec City on September  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"link","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-14495","post","type-post","status-publish","format-link","hentry","category-uncategorized","post_format-post-format-link"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The 2019 gathering, a great success - Levasseur Association of America Inc<\/title>\n<meta name=\"description\" content=\"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The 2019 gathering, a great success - Levasseur Association of America Inc\" \/>\n<meta property=\"og:description\" content=\"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/\" \/>\n<meta property=\"og:site_name\" content=\"Levasseur Association of America Inc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/associationlevasseur\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-15T09:50:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-20T18:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Levasseur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean-Pierre Levasseur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/\"},\"author\":{\"name\":\"Jean-Pierre Levasseur\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/person\\\/08aca2b2e8f0aaeb4fd1ba151d381668\"},\"headline\":\"The 2019 gathering, a great success\",\"datePublished\":\"2019-09-15T09:50:48+00:00\",\"dateModified\":\"2019-09-20T18:43:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/\"},\"wordCount\":51,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Quebec_2019_1.jpg\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/\",\"url\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/\",\"name\":\"The 2019 gathering, a great success - Levasseur Association of America Inc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Quebec_2019_1.jpg\",\"datePublished\":\"2019-09-15T09:50:48+00:00\",\"dateModified\":\"2019-09-20T18:43:17+00:00\",\"description\":\"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#primaryimage\",\"url\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Quebec_2019_1.jpg\",\"contentUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Quebec_2019_1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/en\\\/the-2019-rally-a-complete-success\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/levasseur.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The 2019 gathering, a great success\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/\",\"name\":\"Familles Levasseur & Carmel\",\"description\":\"Du mieux que je puis\",\"publisher\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#organization\",\"name\":\"Association des Levasseur d'Am\u00e9rique\",\"url\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/blason_nouv.gif\",\"contentUrl\":\"https:\\\/\\\/levasseur.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/blason_nouv.gif\",\"width\":500,\"height\":487,\"caption\":\"Association des Levasseur d'Am\u00e9rique\"},\"image\":{\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/associationlevasseur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/levasseur.org\\\/fr\\\/#\\\/schema\\\/person\\\/08aca2b2e8f0aaeb4fd1ba151d381668\",\"name\":\"Jean-Pierre Levasseur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g\",\"caption\":\"Jean-Pierre Levasseur\"},\"description\":\"B\u00e9n\u00e9vole pour l'Association des Levasseur d'Am\u00e9rique depuis 1995.\",\"url\":\"https:\\\/\\\/levasseur.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The 2019 gathering, a great success - Levasseur Association of America Inc","description":"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/","og_locale":"en_US","og_type":"article","og_title":"The 2019 gathering, a great success - Levasseur Association of America Inc","og_description":"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.","og_url":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/","og_site_name":"Levasseur Association of America Inc","article_publisher":"https:\/\/www.facebook.com\/associationlevasseur","article_published_time":"2019-09-15T09:50:48+00:00","article_modified_time":"2019-09-20T18:43:17+00:00","og_image":[{"url":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg","type":"","width":"","height":""}],"author":"Jean-Pierre Levasseur","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jean-Pierre Levasseur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#article","isPartOf":{"@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/"},"author":{"name":"Jean-Pierre Levasseur","@id":"https:\/\/levasseur.org\/fr\/#\/schema\/person\/08aca2b2e8f0aaeb4fd1ba151d381668"},"headline":"The 2019 gathering, a great success","datePublished":"2019-09-15T09:50:48+00:00","dateModified":"2019-09-20T18:43:17+00:00","mainEntityOfPage":{"@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/"},"wordCount":51,"commentCount":0,"publisher":{"@id":"https:\/\/levasseur.org\/fr\/#organization"},"image":{"@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#primaryimage"},"thumbnailUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/","url":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/","name":"The 2019 gathering, a great success - Levasseur Association of America Inc","isPartOf":{"@id":"https:\/\/levasseur.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#primaryimage"},"image":{"@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#primaryimage"},"thumbnailUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg","datePublished":"2019-09-15T09:50:48+00:00","dateModified":"2019-09-20T18:43:17+00:00","description":"L\u2019Association des Levasseur et Carmel d\u2019Am\u00e9rique vous permet de consulter : documents historiques concernant les anc\u00eatres Jean, Pierre et Laurent Levasseur arriv\u00e9s en Nouvelle-France au 17e si\u00e8cle. Informations, objectifs, activit\u00e9s et rassemblements.","breadcrumb":{"@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#primaryimage","url":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg","contentUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/09\/Quebec_2019_1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/levasseur.org\/en\/the-2019-rally-a-complete-success\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/levasseur.org\/en\/"},{"@type":"ListItem","position":2,"name":"The 2019 gathering, a great success"}]},{"@type":"WebSite","@id":"https:\/\/levasseur.org\/fr\/#website","url":"https:\/\/levasseur.org\/fr\/","name":"Familles Levasseur & Carmel","description":"Du mieux que je puis","publisher":{"@id":"https:\/\/levasseur.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/levasseur.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/levasseur.org\/fr\/#organization","name":"Association des Levasseur d'Am\u00e9rique","url":"https:\/\/levasseur.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/levasseur.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/04\/blason_nouv.gif","contentUrl":"https:\/\/levasseur.org\/wp-content\/uploads\/2019\/04\/blason_nouv.gif","width":500,"height":487,"caption":"Association des Levasseur d'Am\u00e9rique"},"image":{"@id":"https:\/\/levasseur.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/associationlevasseur"]},{"@type":"Person","@id":"https:\/\/levasseur.org\/fr\/#\/schema\/person\/08aca2b2e8f0aaeb4fd1ba151d381668","name":"Jean-Pierre Levasseur","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91886ceaeeed70d2c783c3cecea227e4168c3850ccd56c136a87175ac5756f75?s=96&d=mm&r=g","caption":"Jean-Pierre Levasseur"},"description":"B\u00e9n\u00e9vole pour l'Association des Levasseur d'Am\u00e9rique depuis 1995.","url":"https:\/\/levasseur.org\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/posts\/14495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/comments?post=14495"}],"version-history":[{"count":0,"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/posts\/14495\/revisions"}],"wp:attachment":[{"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/media?parent=14495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/categories?post=14495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/levasseur.org\/en\/wp-json\/wp\/v2\/tags?post=14495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}